{"id":4798,"date":"2026-03-18T16:21:46","date_gmt":"2026-03-18T19:21:46","guid":{"rendered":"https:\/\/www.universal-assistance.com\/cl\/?page_id=4798"},"modified":"2026-07-07T01:10:56","modified_gmt":"2026-07-07T04:10:56","slug":"consultas-app","status":"publish","type":"page","link":"https:\/\/www.universal-assistance.com\/cl\/consultas-app","title":{"rendered":"Consultas App y Mi Cobertura"},"content":{"rendered":"\r\n<section class=\"block-formulario \">\r\n    <div class=\"container\">\r\n\r\n        <div class=\"back\">\r\n                            <a href=\"https:\/\/www.universal-assistance.com\/cl\/centro-de-ayuda\">Volver al Centro de ayuda<\/a>\r\n                        <\/div>\r\n\r\n            <form class=\"contacto-form child\" data-motivo=\"\" novalidate>\r\n        <div class=\"contacto-form__title\">\r\n            <h2>Consultas App y Mi Cobertura<\/h2>\r\n            <span>* campos requeridos<\/span>\r\n        <\/div>\r\n        <div class=\"contacto-form__fields\">\r\n            <div class=\"contacto-field contacto-field--select contacto-field--w\">\r\n              <label for=\"contacto-motivo\">\r\n                Motivo                <span class=\"contacto-field__required\" aria-hidden=\"true\">*<\/span>\r\n              <\/label>\r\n                <div class=\"custom-select\" data-select>\r\n                    <button class=\"select-trigger\" type=\"button\">\r\n                      <span data-value>\r\n                        Selecciona un motivo *                      <\/span>                        <span class=\"select-arrow\"><\/span>\r\n                    <\/button>\r\n                    <ul class=\"select-options\">\r\n                                                    <li data-option=\"4777\">\r\n                                Ingreso o Registro                            <\/li>\r\n                                                    <li data-option=\"4779\">\r\n                                Modificar mi informaci\u00f3n                            <\/li>\r\n                                                    <li data-option=\"4778\">\r\n                                Solicitud de Asistencia                            <\/li>\r\n                                                    <li data-option=\"4780\">\r\n                                Mi cobertura en la APP                            <\/li>\r\n                                                    <li data-option=\"5040\">\r\n                                Modificaci\u00f3n datos de login                            <\/li>\r\n                                                    <li data-option=\"5041\">\r\n                                Eliminaci\u00f3n de cuenta                            <\/li>\r\n                                            <\/ul>\r\n                    <input type=\"hidden\" id=\"contacto-motivo\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"contacto-field contacto-field--select contacto-field--wsemi\">\r\n                <div class=\"contacto-custom-msg\">\r\n                  <p id=\"var-msg\">\r\n                  Seleccione el motivo para continuar                  <\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/form>\r\n    <div id=\"contacto-form-dinamico\"><\/div>\r\n    \r\n    <\/div>\r\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates-page\/formularios.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4798","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Consultas App y Mi Cobertura - Chile<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consultas App y Mi Cobertura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.universal-assistance.com\/cl\/consultas-app\" \/>\n<meta property=\"og:site_name\" content=\"Chile\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Universal-Assistance-SA\/296235354195\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T04:10:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@universalassist\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/consultas-app\",\"url\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/consultas-app\",\"name\":\"Consultas App y Mi Cobertura - Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/#website\"},\"datePublished\":\"2026-03-18T19:21:46+00:00\",\"dateModified\":\"2026-07-07T04:10:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/consultas-app#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/consultas-app\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/consultas-app#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consultas App y Mi Cobertura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/\",\"name\":\"Universal Assistance\",\"description\":\"Asegur\u00e1 tu Viaje, Asistencia al Viajero, Asistencia M\u00e9dica, Cobertura de Equipaje, Seguro de Documentaci\u00f3n, Seguro de Viaje\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/#organization\",\"name\":\"Universal Assistance\",\"url\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Universal Assistance\"},\"image\":{\"@id\":\"https:\\\/\\\/www.universal-assistance.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Universal-Assistance-SA\\\/296235354195\",\"https:\\\/\\\/x.com\\\/universalassist\",\"https:\\\/\\\/www.instagram.com\\\/universal.assistance\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/universal-assistance-s-a-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYaYk0Q3CyyTj7fHAVChMGQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Consultas App y Mi Cobertura - Chile","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Consultas App y Mi Cobertura","og_url":"https:\/\/www.universal-assistance.com\/cl\/consultas-app","og_site_name":"Chile","article_publisher":"https:\/\/www.facebook.com\/pages\/Universal-Assistance-SA\/296235354195","article_modified_time":"2026-07-07T04:10:56+00:00","twitter_card":"summary_large_image","twitter_site":"@universalassist","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.universal-assistance.com\/cl\/consultas-app","url":"https:\/\/www.universal-assistance.com\/cl\/consultas-app","name":"Consultas App y Mi Cobertura - Chile","isPartOf":{"@id":"https:\/\/www.universal-assistance.com\/cl\/#website"},"datePublished":"2026-03-18T19:21:46+00:00","dateModified":"2026-07-07T04:10:56+00:00","breadcrumb":{"@id":"https:\/\/www.universal-assistance.com\/cl\/consultas-app#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.universal-assistance.com\/cl\/consultas-app"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.universal-assistance.com\/cl\/consultas-app#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.universal-assistance.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Consultas App y Mi Cobertura"}]},{"@type":"WebSite","@id":"https:\/\/www.universal-assistance.com\/cl\/#website","url":"https:\/\/www.universal-assistance.com\/cl\/","name":"Universal Assistance","description":"Asegur\u00e1 tu Viaje, Asistencia al Viajero, Asistencia M\u00e9dica, Cobertura de Equipaje, Seguro de Documentaci\u00f3n, Seguro de Viaje","publisher":{"@id":"https:\/\/www.universal-assistance.com\/cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.universal-assistance.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/www.universal-assistance.com\/cl\/#organization","name":"Universal Assistance","url":"https:\/\/www.universal-assistance.com\/cl\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.universal-assistance.com\/cl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Universal Assistance"},"image":{"@id":"https:\/\/www.universal-assistance.com\/cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Universal-Assistance-SA\/296235354195","https:\/\/x.com\/universalassist","https:\/\/www.instagram.com\/universal.assistance\/","https:\/\/www.linkedin.com\/company\/universal-assistance-s-a-","https:\/\/www.youtube.com\/channel\/UCYaYk0Q3CyyTj7fHAVChMGQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/pages\/4798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/comments?post=4798"}],"version-history":[{"count":0,"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/pages\/4798\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.universal-assistance.com\/cl\/wp-json\/wp\/v2\/media?parent=4798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}